{"id":11910,"date":"2021-10-13T18:44:07","date_gmt":"2021-10-13T18:44:07","guid":{"rendered":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/"},"modified":"2022-04-07T12:29:03","modified_gmt":"2022-04-07T20:29:03","slug":"powerschool-login","status":"publish","type":"resources","link":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/","title":{"rendered":"Powerschool Login"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","tags":[143,196],"class_list":["post-11910","resources","type-resources","status-publish","hentry","tag-all-school","tag-homepage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Powerschool Login - High Tech High International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Powerschool Login - High Tech High International\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/\" \/>\n<meta property=\"og:site_name\" content=\"High Tech High International\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T20:29:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/resources\\\/powerschool-login\\\/\",\"url\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/resources\\\/powerschool-login\\\/\",\"name\":\"Powerschool Login - High Tech High International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#website\"},\"datePublished\":\"2021-10-13T18:44:07+00:00\",\"dateModified\":\"2022-04-07T20:29:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/resources\\\/powerschool-login\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/resources\\\/powerschool-login\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/resources\\\/powerschool-login\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Powerschool Login\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#website\",\"url\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/\",\"name\":\"High Tech High International\",\"description\":\"Just another High Tech High Network site\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#organization\",\"name\":\"High Tech High International\",\"url\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/07\\\/070225_HTH_international_horizontal_fullcolor_RGB.svg\",\"contentUrl\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/07\\\/070225_HTH_international_horizontal_fullcolor_RGB.svg\",\"width\":1641,\"height\":170,\"caption\":\"High Tech High International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hightechhigh.org\\\/hthi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Powerschool Login - High Tech High International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/","og_locale":"en_US","og_type":"article","og_title":"Powerschool Login - High Tech High International","og_url":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/","og_site_name":"High Tech High International","article_modified_time":"2022-04-07T20:29:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/","url":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/","name":"Powerschool Login - High Tech High International","isPartOf":{"@id":"https:\/\/www.hightechhigh.org\/hthi\/#website"},"datePublished":"2021-10-13T18:44:07+00:00","dateModified":"2022-04-07T20:29:03+00:00","breadcrumb":{"@id":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hightechhigh.org\/hthi\/resources\/powerschool-login\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hightechhigh.org\/hthi\/"},{"@type":"ListItem","position":2,"name":"Powerschool Login"}]},{"@type":"WebSite","@id":"https:\/\/www.hightechhigh.org\/hthi\/#website","url":"https:\/\/www.hightechhigh.org\/hthi\/","name":"High Tech High International","description":"Just another High Tech High Network site","publisher":{"@id":"https:\/\/www.hightechhigh.org\/hthi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hightechhigh.org\/hthi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hightechhigh.org\/hthi\/#organization","name":"High Tech High International","url":"https:\/\/www.hightechhigh.org\/hthi\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hightechhigh.org\/hthi\/#\/schema\/logo\/image\/","url":"https:\/\/www.hightechhigh.org\/hthi\/wp-content\/uploads\/sites\/18\/2025\/07\/070225_HTH_international_horizontal_fullcolor_RGB.svg","contentUrl":"https:\/\/www.hightechhigh.org\/hthi\/wp-content\/uploads\/sites\/18\/2025\/07\/070225_HTH_international_horizontal_fullcolor_RGB.svg","width":1641,"height":170,"caption":"High Tech High International"},"image":{"@id":"https:\/\/www.hightechhigh.org\/hthi\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.hightechhigh.org\/hthi\/wp-json\/wp\/v2\/resources\/11910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hightechhigh.org\/hthi\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/www.hightechhigh.org\/hthi\/wp-json\/wp\/v2\/types\/resources"}],"wp:attachment":[{"href":"https:\/\/www.hightechhigh.org\/hthi\/wp-json\/wp\/v2\/media?parent=11910"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hightechhigh.org\/hthi\/wp-json\/wp\/v2\/tags?post=11910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}